{"id":167,"count":1,"description":"","link":"https:\/\/www.ippocrateshop.com\/blog\/tag\/ecg-a-distanza\/","name":"ecg a distanza","slug":"ecg-a-distanza","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ecg a distanza &#060; IppocrateShop Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ippocrateshop.com\/blog\/tag\/ecg-a-distanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ecg a distanza &#060; IppocrateShop Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ippocrateshop.com\/blog\/tag\/ecg-a-distanza\/\" \/>\n<meta property=\"og:site_name\" content=\"IppocrateShop Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/tag\\\/ecg-a-distanza\\\/\",\"url\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/tag\\\/ecg-a-distanza\\\/\",\"name\":\"ecg a distanza &#060; IppocrateShop Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/tag\\\/ecg-a-distanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/tag\\\/ecg-a-distanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"IppocrateshopBlog\",\"item\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ecg a distanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/\",\"name\":\"IppocrateShop Blog\",\"description\":\"Il Blog delle apparecchiature medicali\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ecg a distanza &#060; IppocrateShop Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ippocrateshop.com\/blog\/tag\/ecg-a-distanza\/","og_locale":"it_IT","og_type":"article","og_title":"ecg a distanza &#060; IppocrateShop Blog","og_url":"https:\/\/www.ippocrateshop.com\/blog\/tag\/ecg-a-distanza\/","og_site_name":"IppocrateShop Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ippocrateshop.com\/blog\/tag\/ecg-a-distanza\/","url":"https:\/\/www.ippocrateshop.com\/blog\/tag\/ecg-a-distanza\/","name":"ecg a distanza &#060; IppocrateShop Blog","isPartOf":{"@id":"https:\/\/www.ippocrateshop.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.ippocrateshop.com\/blog\/tag\/ecg-a-distanza\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ippocrateshop.com\/blog\/tag\/ecg-a-distanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"IppocrateshopBlog","item":"https:\/\/www.ippocrateshop.com\/blog\/"},{"@type":"ListItem","position":2,"name":"ecg a distanza"}]},{"@type":"WebSite","@id":"https:\/\/www.ippocrateshop.com\/blog\/#website","url":"https:\/\/www.ippocrateshop.com\/blog\/","name":"IppocrateShop Blog","description":"Il Blog delle apparecchiature medicali","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ippocrateshop.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/tags\/167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/posts?tags=167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}