{"id":264,"date":"2017-02-24T11:59:36","date_gmt":"2017-02-24T10:59:36","guid":{"rendered":"http:\/\/www.ippocrateshop.com\/blog\/?p=264"},"modified":"2017-02-25T10:12:21","modified_gmt":"2017-02-25T09:12:21","slug":"interpretare-un-ecg-neonatale","status":"publish","type":"post","link":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/","title":{"rendered":"Interpretare un ecg neonatale"},"content":{"rendered":"<p>Per poter interpretare al meglio un ecg neonatale, oltre ad avere un <a href=\"http:\/\/www.ippocrateshop.com\/elettrocardiografi\/331-elettrocardiografo-portatile-interpretativo-a-12-derivazioni-e-6-canali-di-stampa-ie6-biocare.html\" target=\"_blank\">elettrocardiografo a 12 derivazioni dotato del filtro passa basso impostabile a 250 Hz<\/a>\u00a0(e non sono molti, ve lo assicuro) come consigliato dalle pi\u00f9 recenti <a href=\"http:\/\/www.ippocrateshop.com\/blog\/ecg-neonatale-e-pediatrico-nuove-linee-guida-sul-filtro-passa-basso\/\" target=\"_blank\">linee guida della AHA<\/a>,\u00a0bisogna conoscere i mutamenti fisici e cardiologici che avvengono dalla gestazione ai primi anni di vita.<\/p>\n<h2>I mutamenti della morfologia del cuore del bambino nei primi anni di vita riscontrabili con un ecg neonatale<\/h2>\n<p><strong>Nel feto la respirazione, nutrizione ed escrezione avvengono attraverso la placenta,<\/strong> quindi polmoni e apparato digerente non sono ancora funzionanti.<\/p>\n<p>Il <strong>cordone ombelicale ha 3 vasi sanguigni<\/strong>:<\/p>\n<ul>\n<li><strong>1 vena ombelicale<\/strong> che trasporta al feto sangue con ossigeno e sostanze nutritizie<\/li>\n<li><strong>2 arterie ombelicali<\/strong> che portano alla placenta CO2 e prodotti di rifiuto<\/li>\n<\/ul>\n<p>Il sangue dalla placenta, per arrivare verso il cuore del feto, attraversa il <strong>dotto venoso<\/strong> e dalla vena cava inferiore arriva all&#8217;atrio destro.<\/p>\n<p><strong>I polmoni, inutili in questa fase della vita, vengono esclusi dalla circolazione con due shunt<\/strong>. Buona parte del <strong>sangue dall&#8217;atrio destro passa a quello sinistro attraverso il forame ovale<\/strong> mentre un&#8217;altra parte passa al ventricolo destro e, successivamente, al tronco polmonare. Qui il <strong>dotto arterioso porta il sangue all&#8217;aorta<\/strong> e, di conseguenza, a tutti i tessuti corporei per tornare infine alla placenta.<\/p>\n<p><strong>Alla nascita<\/strong> il<strong> forame ovale<\/strong> <strong>si chiude<\/strong> ed il <strong>dotto arterioso muta in legamento arterioso.<\/strong><\/p>\n<p>I vasi ombelicali non pi\u00f9 irrorati e si chiudono cos\u00ec il modello di circolazione diventa uguale a quello adulto.<\/p>\n<p><a href=\"http:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/circolazione_sanguigna_fetale\/\" rel=\"attachment wp-att-265\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-265\" src=\"http:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/circolazione_sanguigna_fetale-179x300.jpg\" alt=\"circolazione sanguigna fetale\" width=\"212\" height=\"355\" srcset=\"https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/circolazione_sanguigna_fetale-179x300.jpg 179w, https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/circolazione_sanguigna_fetale.jpg 351w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n<p>Oltre a questo, va analizzata l&#8217;<strong>evoluzione del ventricolo sinistro<\/strong> che passa da una proporzione di <strong>1,5:1<\/strong> (Ventricolo sinistro\/ventricolo destro) al <strong>primo mese<\/strong> di vita rispetto al <strong>0,8:1<\/strong> della<strong> nascita.<\/strong>\u00a0Arriver\u00e0 al <strong>sesto mese<\/strong> di vita a<strong> 2:1<\/strong> e lentamente raggiunger\u00e0 i <strong>2,5:1 dell&#8217;et\u00e0 adulta<\/strong>.<\/p>\n<p>Con questa emodinamica in continua evoluzione \u00e8 ovvio che l&#8217;interpretazione di un <strong>ecg neonatale richieda un&#8217;attenzione massima<\/strong> e delle conoscenze specifiche. Oltre, naturalmente, ad <strong>un ottimo elettrocardiografo<\/strong>.<\/p>\n<p>Un bambino prematuro avr\u00e0 un tracciato elettrocardiografico differente da quello di un bambino nato a termine della gestazione. Questi, a sua volta, avr\u00e0 un tracciato\u00a0differente da quello di un bambino di 6 mesi, 1 anno, 2 anni ecc&#8230;<\/p>\n<p><strong>Il tracciato ecg del bambino inizia a diventare simile a quello di un adulto solo dopo i 3 anni di vita.<\/strong><\/p>\n<p>Tuttavia, persisteranno ancora delle differenze che il medico deve\u00a0conoscere per non far diventare il suo giovane paziente una &#8220;vittima dell&#8217;elettrocardiografo&#8221;. Un rischio derivante da interpretazioni errate e conclusioni non consone.<\/p>\n<p>Per interpretare al meglio un ecg neonatale e pediatrico, il medico dovr\u00e0 avere una tabella corrispondente ai mutamenti cardiologici che avvengono in ogni fase della crescita.<\/p>\n<h3>Le variazioni pi\u00f9 importanti che avvengono a livello cardiologico riscontrabili in un ecg neonatale e pediatrico<\/h3>\n<p>Il <strong>tracciato elettrocardiografico di un neonato e di una bambino fino ai tre anni di vita<\/strong> sono differenti da quello di un adulto.\u00a0Le differenze riguardano l&#8217;<strong>inversione dell&#8217;onda T<\/strong>, l&#8217;<strong>elevato punto J<\/strong> e l&#8217;<strong>altezza di R.\u00a0<\/strong><\/p>\n<h4>Inversione dell&#8217;onda T nell&#8217;ecg neonatale e pediatrico<\/h4>\n<p>I bambini con un&#8217;<strong>et\u00e0 superiore alle 48 ore di vita<\/strong> dovrebbero avere le <strong>onde T invertire nelle derivazioni precordiali<\/strong>. Questa inversione persister\u00e0 per tutta l&#8217;infanzia con un&#8217;inversione soprattutto in V4 che sar\u00e0 accettata come normale. Vi \u00e8 un progressivo cambiamento dell&#8217;onda T nelle derivazioni precordiali da sinistra a destra che si accompagna alla crescita del bambino.<\/p>\n<p>Fino agli 8 anni di et\u00e0 un&#8217;onda T in posizione verticale in V1 \u00e8 considerata un segno di ipertrofia ventricolare destra.<\/p>\n<p><strong>Molti bambini mostreranno la persistenza di un&#8217;onda T rovesciata in V1 fino a tarda adolescenza.<\/strong><\/p>\n<h4>Elevato punto J nell&#8217;ecg neonatale e pediatrico<\/h4>\n<p><strong>Il punto J con una elevata e precoce ripolarizzazione \u00e8 comune nell&#8217;adolescenza; ed \u00e8 molto pi\u00f9 evidente nelle derivazioni precordiali<\/strong>. Questo \u00e8 del tutto normale in un elettrocardiogramma pediatrico e va distinta da un&#8217;elevazione patologica dei segmenti ST.<\/p>\n<h4>Complesso RSR nell&#8217;ecg neonatale e pediatrico<\/h4>\n<p>Per essere considerata <strong>non patologica<\/strong> la larghezza del <strong>QRS non dovrebbe eccedere i 10 millisecondi rispetto a ci\u00f2 che noi consideriamo normale<\/strong> e la tensione del punto <strong>R in V1 deve essere inferiore a 15 mm nei neonati<\/strong> sotto il primo anno di vita e <strong>meno di 10 mm oltre l&#8217;anno<\/strong>.<\/p>\n<h3>In che modo schematizzare e leggere un ecg neonatale e pediatrico<\/h3>\n<p>Un <strong>ecg neonatale e pediatrico per essere interpretato al meglio va schematizzato e bisogna seguire una cronologia impostata<\/strong>.<\/p>\n<p>Si parte analizzando la frequenza cardiaca, si passa ad analizzare l&#8217;asse dell&#8217;onda P, il ritmo e l&#8217;asse del QRS. Successivamente si misureranno gli intervalli PR-QRr-<a href=\"http:\/\/www.ippocrateshop.com\/blog\/ecg-neonatale-e-pediatrico-riconoscere-il-qt-lungo\/\" target=\"_blank\">QT\/QTc<\/a>, ampiezza e durata dell&#8217;onda P, il rapporto R\/S e l&#8217;onda Q per treminare con lo studio del segmento ST e dell&#8217;onda T.<\/p>\n<p>Qundi, per essere pi\u00f9 precisi e meno confusionari, nel momento in cui mi trovo di fronte ad un ecg neonatale e pediatrico dovr\u00f2:<\/p>\n<ul>\n<li>Analizzare la <strong>Frequenza Cardiac<\/strong>a<\/li>\n<li>Analizzare l&#8217;asse dell&#8217;<strong>onda P<\/strong><\/li>\n<li>Analizzare il<strong> ritmo<\/strong><\/li>\n<li>Analizzare l&#8217;<strong>asse del QRS<\/strong><\/li>\n<li>Studiare gli intervalli <strong>PR-QRS-QT\/QTc<\/strong><\/li>\n<li>Ampiezza e durata dell&#8217;<strong>onda P<\/strong><\/li>\n<li>Ampiezza del complesso <strong>QRS<\/strong>, rapporto<strong> R\/S<\/strong> e onda<strong> Q<\/strong><\/li>\n<li>Analisi del <strong>segmento ST e dell&#8217;onda T<\/strong><\/li>\n<\/ul>\n<h3>Evoluzione e caratteristiche di un tracciato ecg neonatale e pediatrico<\/h3>\n<p>Adesso vediamo alcuni\u00a0esempi per capire al meglio come si evolve l&#8217;ecg di un bambino dal primo giorno di vita ai 6 anni.<\/p>\n<div id=\"attachment_266\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/ecg_neonatale_1_giorno_di_vita\/\" rel=\"attachment wp-att-266\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-266\" class=\"size-medium wp-image-266\" src=\"http:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_1_giorno_di_vita-300x143.jpg\" alt=\"ecg neonatale 1 giorno di vita\" width=\"300\" height=\"143\" srcset=\"https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_1_giorno_di_vita-300x143.jpg 300w, https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_1_giorno_di_vita.jpg 689w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-266\" class=\"wp-caption-text\">ecg neonatale 1 giorno di vita<\/p><\/div>\n<p>Possiamo notare una deviazione sull&#8217;asse destro con una predominanza del ventricolo destro (R in V1 maggiore di 10 mm, S bassa in V6, rapporto R\/S maggiore di 1), QRS con voltaggio relativamente basso nelle precordiali, basso voltaggio dell&#8217;onda T.<\/p>\n<p>125 Bpm di Frequenza Cardiaca con ritmo sinusale<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_267\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/ecg_neonatale_2_giorni_di_vita\/\" rel=\"attachment wp-att-267\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-267\" class=\"size-medium wp-image-267\" src=\"http:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_2_giorni_di_vita-300x128.jpg\" alt=\"ecg neonatale 2 giorni di vita\" width=\"300\" height=\"128\" srcset=\"https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_2_giorni_di_vita-300x128.jpg 300w, https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_2_giorni_di_vita.jpg 711w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-267\" class=\"wp-caption-text\">ecg neonatale 2 giorni di vita<\/p><\/div>\n<p>Rimane dominante l&#8217;asse destro, R sempre pi\u00f9 alta in V6, onda T negativa in V1 e con voltaggio pi\u00f9 alto nelle periferiche<\/p>\n<p>Ritmo sinusale con 130 Bpm di frequenza cardiaca<\/p>\n<div id=\"attachment_268\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/ecg_neonatale_8_mesi_di_vita\/\" rel=\"attachment wp-att-268\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-268\" class=\"size-medium wp-image-268\" src=\"http:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_8_mesi_di_vita-300x149.jpg\" alt=\"ecg neonatale 8 mesi di vita\" width=\"300\" height=\"149\" srcset=\"https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_8_mesi_di_vita-300x149.jpg 300w, https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_8_mesi_di_vita.jpg 631w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-268\" class=\"wp-caption-text\">ecg neonatale 8 mesi di vita<\/p><\/div>\n<p>R dominante in V6, rapporto R\/S in V1 vicino a 1, l&#8217;alto voltaggio nelle precordiali persiste.<\/p>\n<p>Ritmo sinusale con 140 Bpm di frequenza cardiaca<\/p>\n<div id=\"attachment_269\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/ecg_pediatrico_6_anni_di_vita\/\" rel=\"attachment wp-att-269\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-269\" class=\"size-medium wp-image-269\" src=\"http:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_pediatrico_6_anni_di_vita-300x131.jpg\" alt=\"ecg pediatrico 6 anni di vita\" width=\"300\" height=\"131\" srcset=\"https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_pediatrico_6_anni_di_vita-300x131.jpg 300w, https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_pediatrico_6_anni_di_vita.jpg 649w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-269\" class=\"wp-caption-text\">ecg pediatrico 6 anni di vita<\/p><\/div>\n<p>Il QRS assomiglia sempre pi\u00f9 a quello di una persona adulta.\u00a0Il voltaggio delle precordiali rimane comunque alto, un punto J molto alto e un&#8217;onda T che tra V1 e V4 pu\u00f2 essere considerata normale anche se negativa<\/p>\n<p>Bibliografia:<\/p>\n<p>Davignon A, Rautaharju P, Boiselle E, Soumis F, Megelas M, Choquette <em>A. Normal ECG standards for infants and children. <span class=\"ref-journal\">Pediatric Cardiology<\/span><\/em><\/p>\n<div id=\"ui-ncbiinpagenav-1\" class=\"jig-ncbiinpagenav\" data-jigconfig=\"smoothScroll: false, allHeadingLevels: ['h2'], headingExclude: ':hidden'\">\n<div id=\"__ref-listid781358\" class=\"tsec sec\">\n<div id=\"reference-list\" class=\"ref-list-sec sec\">\n<div id=\"ref6\" class=\"ref-cit-blk half_rhythm\"><span class=\"element-citation\">Myung K, Park MK, Guntheroth WG. St. Louis: Mosby Year Book; 1992. <em>How To Read Pediatric ECGs<\/em>.<\/span><\/div>\n<div class=\"ref-cit-blk half_rhythm\"><\/div>\n<\/div>\n<div class=\"ref-cit-blk half_rhythm\">Garson A. Electrocardiography. In: Anderson RH, Macartney FJ, Shinebourne EA, Tynan M, editors. <span class=\"ref-journal\"><em>Paediatric Cardiology<\/em>.<\/span> Edinburgh: Churchill Livingstone; 1987. pp. 235\u2013317.<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per poter interpretare al meglio un ecg neonatale, oltre ad avere un elettrocardiografo a 12 derivazioni dotato del filtro passa basso impostabile a 250 Hz\u00a0(e&#8230;<\/p>\n","protected":false},"author":1,"featured_media":266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[39,34,49],"class_list":["post-264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guide-e-test-dispositivi-medicali","tag-ecg-pediatra","tag-elettrocardiografi","tag-elettrocardiografo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interpretare un ecg neonatale &#060; IppocrateShop Blog<\/title>\n<meta name=\"description\" content=\"Interpretare al meglio un ecg neonatale conoscendo le evoluzioni morfologiche del cuore del bambino dal primo giorno di vita all&#039;adolescenza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interpretare un ecg neonatale &#060; IppocrateShop Blog\" \/>\n<meta property=\"og:description\" content=\"Interpretare al meglio un ecg neonatale conoscendo le evoluzioni morfologiche del cuore del bambino dal primo giorno di vita all&#039;adolescenza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/\" \/>\n<meta property=\"og:site_name\" content=\"IppocrateShop Blog\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-24T10:59:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-25T09:12:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_1_giorno_di_vita.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"689\" \/>\n\t<meta property=\"og:image:height\" content=\"328\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"simona giulieri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"simona giulieri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/\"},\"author\":{\"name\":\"simona giulieri\",\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/#\\\/schema\\\/person\\\/1b80b77f23ff08a4acf2625d6d0c5163\"},\"headline\":\"Interpretare un ecg neonatale\",\"datePublished\":\"2017-02-24T10:59:36+00:00\",\"dateModified\":\"2017-02-25T09:12:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/\"},\"wordCount\":1085,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ecg_neonatale_1_giorno_di_vita.jpg\",\"keywords\":[\"ecg pediatra\",\"elettrocardiografi\",\"elettrocardiografo\"],\"articleSection\":[\"Guide e test dispositivi medicali\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/\",\"url\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/\",\"name\":\"Interpretare un ecg neonatale &#060; IppocrateShop Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ecg_neonatale_1_giorno_di_vita.jpg\",\"datePublished\":\"2017-02-24T10:59:36+00:00\",\"dateModified\":\"2017-02-25T09:12:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/#\\\/schema\\\/person\\\/1b80b77f23ff08a4acf2625d6d0c5163\"},\"description\":\"Interpretare al meglio un ecg neonatale conoscendo le evoluzioni morfologiche del cuore del bambino dal primo giorno di vita all'adolescenza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ecg_neonatale_1_giorno_di_vita.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ecg_neonatale_1_giorno_di_vita.jpg\",\"width\":689,\"height\":328,\"caption\":\"ecg neonatale 1 giorno di vita\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/interpretare-un-ecg-neonatale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"IppocrateshopBlog\",\"item\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guide e test dispositivi medicali\",\"item\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/category\\\/guide-e-test-dispositivi-medicali\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Interpretare un ecg neonatale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/\",\"name\":\"IppocrateShop Blog\",\"description\":\"Il Blog delle apparecchiature medicali\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/#\\\/schema\\\/person\\\/1b80b77f23ff08a4acf2625d6d0c5163\",\"name\":\"simona giulieri\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1f21eb1c20fc618016c5dd2cdf3e711c971fa89ef828f5ac695776e1f822066?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1f21eb1c20fc618016c5dd2cdf3e711c971fa89ef828f5ac695776e1f822066?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1f21eb1c20fc618016c5dd2cdf3e711c971fa89ef828f5ac695776e1f822066?s=96&d=mm&r=g\",\"caption\":\"simona giulieri\"},\"url\":\"https:\\\/\\\/www.ippocrateshop.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interpretare un ecg neonatale &#060; IppocrateShop Blog","description":"Interpretare al meglio un ecg neonatale conoscendo le evoluzioni morfologiche del cuore del bambino dal primo giorno di vita all'adolescenza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/","og_locale":"it_IT","og_type":"article","og_title":"Interpretare un ecg neonatale &#060; IppocrateShop Blog","og_description":"Interpretare al meglio un ecg neonatale conoscendo le evoluzioni morfologiche del cuore del bambino dal primo giorno di vita all'adolescenza","og_url":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/","og_site_name":"IppocrateShop Blog","article_published_time":"2017-02-24T10:59:36+00:00","article_modified_time":"2017-02-25T09:12:21+00:00","og_image":[{"width":689,"height":328,"url":"https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_1_giorno_di_vita.jpg","type":"image\/jpeg"}],"author":"simona giulieri","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"simona giulieri","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/#article","isPartOf":{"@id":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/"},"author":{"name":"simona giulieri","@id":"https:\/\/www.ippocrateshop.com\/blog\/#\/schema\/person\/1b80b77f23ff08a4acf2625d6d0c5163"},"headline":"Interpretare un ecg neonatale","datePublished":"2017-02-24T10:59:36+00:00","dateModified":"2017-02-25T09:12:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/"},"wordCount":1085,"commentCount":0,"image":{"@id":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_1_giorno_di_vita.jpg","keywords":["ecg pediatra","elettrocardiografi","elettrocardiografo"],"articleSection":["Guide e test dispositivi medicali"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/","url":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/","name":"Interpretare un ecg neonatale &#060; IppocrateShop Blog","isPartOf":{"@id":"https:\/\/www.ippocrateshop.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/#primaryimage"},"image":{"@id":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_1_giorno_di_vita.jpg","datePublished":"2017-02-24T10:59:36+00:00","dateModified":"2017-02-25T09:12:21+00:00","author":{"@id":"https:\/\/www.ippocrateshop.com\/blog\/#\/schema\/person\/1b80b77f23ff08a4acf2625d6d0c5163"},"description":"Interpretare al meglio un ecg neonatale conoscendo le evoluzioni morfologiche del cuore del bambino dal primo giorno di vita all'adolescenza","breadcrumb":{"@id":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/#primaryimage","url":"https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_1_giorno_di_vita.jpg","contentUrl":"https:\/\/www.ippocrateshop.com\/blog\/wp-content\/uploads\/2017\/02\/ecg_neonatale_1_giorno_di_vita.jpg","width":689,"height":328,"caption":"ecg neonatale 1 giorno di vita"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ippocrateshop.com\/blog\/interpretare-un-ecg-neonatale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"IppocrateshopBlog","item":"https:\/\/www.ippocrateshop.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Guide e test dispositivi medicali","item":"https:\/\/www.ippocrateshop.com\/blog\/category\/guide-e-test-dispositivi-medicali\/"},{"@type":"ListItem","position":3,"name":"Interpretare un ecg neonatale"}]},{"@type":"WebSite","@id":"https:\/\/www.ippocrateshop.com\/blog\/#website","url":"https:\/\/www.ippocrateshop.com\/blog\/","name":"IppocrateShop Blog","description":"Il Blog delle apparecchiature medicali","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ippocrateshop.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.ippocrateshop.com\/blog\/#\/schema\/person\/1b80b77f23ff08a4acf2625d6d0c5163","name":"simona giulieri","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c1f21eb1c20fc618016c5dd2cdf3e711c971fa89ef828f5ac695776e1f822066?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c1f21eb1c20fc618016c5dd2cdf3e711c971fa89ef828f5ac695776e1f822066?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1f21eb1c20fc618016c5dd2cdf3e711c971fa89ef828f5ac695776e1f822066?s=96&d=mm&r=g","caption":"simona giulieri"},"url":"https:\/\/www.ippocrateshop.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/posts\/264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/comments?post=264"}],"version-history":[{"count":7,"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/posts\/264\/revisions"}],"predecessor-version":[{"id":277,"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/posts\/264\/revisions\/277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/media\/266"}],"wp:attachment":[{"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/media?parent=264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/categories?post=264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ippocrateshop.com\/blog\/wp-json\/wp\/v2\/tags?post=264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}